{"id":16827,"date":"2021-06-17T00:36:43","date_gmt":"2021-06-17T00:36:43","guid":{"rendered":"https:\/\/www.cafoodbanks.org\/?page_id=16827"},"modified":"2021-07-07T23:01:16","modified_gmt":"2021-07-07T23:01:16","slug":"logo-toolkit","status":"publish","type":"page","link":"https:\/\/www.cafoodbanks.org\/es\/logo-toolkit\/","title":{"rendered":"CAFB Logo Toolkit"},"content":{"rendered":"<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-foursite-gutenberg-blocks-collapsible-block alignwide collapsible-content-block\"><h2 class=\"trigger label\">Logo Files<\/h2><div class=\"description wrapper\"><\/div><div class=\"content wrapper\">\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>PNG Logo Files<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>SVG Logo Files<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>AI Logo Files <\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>All Logo Files<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/drive\/folders\/1lzfFHRbpb1j6Jw3moxcY8piY9jD573Nw?usp=sharing\" target=\"_blank\">DOWNLOAD<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/drive\/folders\/1CMEQnAlQmzEUfXbVNcHBhqEdaDkJMFFy?usp=sharing\" target=\"_blank\">DOWNLOAD<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/drive\/folders\/1CExElgye8hfRQPAr37VpNvc3dhS0NWDA?usp=sharing\" target=\"_blank\">DOWNLOAD<\/a><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong><a rel=\"noreferrer noopener\" href=\"https:\/\/drive.google.com\/drive\/folders\/1D-7t1d0YvJAccjZl1s71A0zLoQ2nEHvP?usp=sharing\" target=\"_blank\">DOWNLOAD<\/a><\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:39px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-2 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"401\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2020\/12\/CAFB-Logo-1024x401.png\" alt=\"\" data-id=\"4780\" data-link=\"https:\/\/www.cafoodbanks.org\/cafb-logo\/\" class=\"wp-image-4780\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2020\/12\/CAFB-Logo-1024x401.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2020\/12\/CAFB-Logo-300x118.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2020\/12\/CAFB-Logo-768x301.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2020\/12\/CAFB-Logo-16x6.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2020\/12\/CAFB-Logo.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Logotipo est\u00e1ndar<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"404\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo_black-1024x404-1.png\" alt=\"\" data-id=\"16829\" data-link=\"https:\/\/www.cafoodbanks.org\/?attachment_id=16829\" class=\"wp-image-16829\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo_black-1024x404-1.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo_black-1024x404-1-300x118.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo_black-1024x404-1-768x303.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo_black-1024x404-1-16x6.png 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Logotipo negro<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"397\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Screen-Shot-2021-06-16-at-2.20.26-PM-e1623878622897-1024x397.png\" alt=\"\" data-id=\"16844\" data-link=\"https:\/\/www.cafoodbanks.org\/?attachment_id=16844\" class=\"wp-image-16844\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Screen-Shot-2021-06-16-at-2.20.26-PM-e1623878622897-1024x397.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Screen-Shot-2021-06-16-at-2.20.26-PM-e1623878622897-300x116.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Screen-Shot-2021-06-16-at-2.20.26-PM-e1623878622897-768x298.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Screen-Shot-2021-06-16-at-2.20.26-PM-e1623878622897-1536x595.png 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Screen-Shot-2021-06-16-at-2.20.26-PM-e1623878622897-2048x793.png 2048w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Screen-Shot-2021-06-16-at-2.20.26-PM-e1623878622897-16x6.png 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Logotipo blanco<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"402\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo-greyscale-1024x402.png\" alt=\"\" data-id=\"16878\" data-link=\"https:\/\/www.cafoodbanks.org\/?attachment_id=16878\" class=\"wp-image-16878\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo-greyscale-1024x402.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo-greyscale-300x118.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo-greyscale-768x301.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo-greyscale-16x6.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/CAFB-Logo-greyscale.png 1527w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">Greyscale Logo<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"423\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_MEMBER-FOOD-BANK-1024x423.png\" alt=\"\" data-id=\"17640\" data-full-url=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_MEMBER-FOOD-BANK.png\" data-link=\"https:\/\/www.cafoodbanks.org\/logo-toolkit\/attachment\/cafb-logo_member-food-bank\/\" class=\"wp-image-17640\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_MEMBER-FOOD-BANK-1024x423.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_MEMBER-FOOD-BANK-300x124.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_MEMBER-FOOD-BANK-768x317.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_MEMBER-FOOD-BANK-16x7.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_MEMBER-FOOD-BANK.png 1427w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">&#8220;Member Food Bank&#8221; Below<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"401\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_PROUD-MEMBER-1024x401.png\" alt=\"\" data-id=\"17641\" data-full-url=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_PROUD-MEMBER.png\" data-link=\"https:\/\/www.cafoodbanks.org\/logo-toolkit\/attachment\/cafb-logo_proud-member\/\" class=\"wp-image-17641\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_PROUD-MEMBER-1024x401.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_PROUD-MEMBER-300x118.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_PROUD-MEMBER-768x301.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_PROUD-MEMBER-16x6.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/07\/CAFB-Logo_PROUD-MEMBER.png 1427w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\">&#8220;Proud Member&#8221; Above<\/figcaption><\/figure><\/li><\/ul><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-foursite-gutenberg-blocks-collapsible-block alignwide collapsible-content-block\"><h2 class=\"trigger label\">Colores<\/h2><div class=\"description wrapper\"><\/div><div class=\"content wrapper\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-white-color has-green-background-color has-text-color has-background\">Verde oscuro<br>CMYK 100\/50\/100\/0<br>RGB 0\/111\/69<br>HEX #006F45<\/p>\n\n\n\n<p class=\"has-white-color has-nasty-green-background-color has-text-color has-background\">Verde claro<br>CMYK 48\/0\/88\/13<br>RGB 127\/178\/74<br>HEX #7FB24A<\/p>\n\n\n\n<p class=\"has-white-color has-mango-background-color has-text-color has-background\">Amarillo<br>CMYK 0\/25\/100\/0<br>RGB 255\/194\/14<br>HEX #FFC20E<\/p>\n\n\n\n<p class=\"has-white-color has-lipstick-background-color has-text-color has-background\">rojo<br>CMYK 20\/100\/98\/13<br>RGB 178\/25\/26<br>HEX #B2191A<\/p>\n\n\n\n<p class=\"has-white-color has-orange-background-color has-text-color has-background\">Orange<br>CMYK 0\/73\/96\/0<br>RGB 235\/96\/24<br>HEX #EB6018<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-grey-color has-text-color has-background\" style=\"background-color:#ececec\">Gris claro<br>CMYK 9\/4\/4\/0<br>RGB 236\/236\/236<br>HEX #ECECEC<\/p>\n\n\n\n<p class=\"has-white-color has-text-color has-background\" style=\"background-color:#626364\">Gris fr\u00edo<br>CMYK 14\/9\/8\/70<br>RGB 98\/100\/101<br>HEX #626364<\/p>\n\n\n\n<p class=\"has-white-color has-black-background-color has-text-color has-background\">Carb\u00f3n<br>CMYK 15\/0\/0\/90<br>RGB 51\/60\/66<br>HEX #33383A<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-foursite-gutenberg-blocks-collapsible-block alignwide collapsible-content-block\"><h2 class=\"trigger label\">Guidelines for Use<\/h2><div class=\"description wrapper\"><\/div><div class=\"content wrapper\">\n<p><strong>CO-BRANDING<\/strong><br>When co-branding, size our logo so that it is visually equal to other logos, creating a minimum clearspace:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/clearspace-1024x654.png\" alt=\"\" class=\"wp-image-16853\" width=\"428\" height=\"273\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/clearspace-1024x654.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/clearspace-300x192.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/clearspace-768x491.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/clearspace-1536x981.png 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/clearspace-2048x1309.png 2048w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/clearspace-16x10.png 16w\" sizes=\"auto, (max-width: 428px) 100vw, 428px\" \/><\/figure>\n\n\n\n<div style=\"height:14px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><em>For Example:<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/co-brand-2-1024x169.png\" alt=\"\" class=\"wp-image-16856\" width=\"407\" height=\"66\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/co-brand-2-1024x169.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/co-brand-2-300x49.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/co-brand-2-768x127.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/co-brand-2-1536x253.png 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/co-brand-2-2048x338.png 2048w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/co-brand-2-16x3.png 16w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/><\/figure>\n\n\n\n<div style=\"height:53px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>WHAT <em>NOT<\/em> TO DO WITH OUR LOGO:<\/strong><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/avoid-844x1024.png\" alt=\"\" class=\"wp-image-16870\" width=\"323\" height=\"392\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/avoid-844x1024.png 844w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/avoid-247x300.png 247w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/avoid-768x931.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/avoid-10x12.png 10w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/avoid.png 1076w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-foursite-gutenberg-blocks-collapsible-block alignwide collapsible-content-block\"><h2 class=\"trigger label\">Co-Branding Examples<\/h2><div class=\"description wrapper\"><\/div><div class=\"content wrapper\">\n<p><em>Most<\/em> of these examples are from REAL use by our members! (Our new logo was swapped in for the old one though):<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>SOCIAL MEDIA:<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-FB-Cover-1024x600.png\" alt=\"\" class=\"wp-image-16889\" width=\"577\" height=\"337\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-FB-Cover-1024x600.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-FB-Cover-300x176.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-FB-Cover-768x450.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-FB-Cover-1536x900.png 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-FB-Cover-16x9.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-FB-Cover.png 1652w\" sizes=\"auto, (max-width: 577px) 100vw, 577px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>WEBSITE:<\/strong><\/h4>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em>Header:<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1436\" height=\"484\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Header.png\" alt=\"\" class=\"wp-image-16890\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Header.png 1436w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Header-300x101.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Header-1024x345.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Header-768x259.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Header-16x5.png 16w\" sizes=\"auto, (max-width: 1436px) 100vw, 1436px\" \/><\/figure>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em>Pre-Footer:<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"345\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-PreFooter-1024x345.png\" alt=\"\" class=\"wp-image-16891\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-PreFooter-1024x345.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-PreFooter-300x101.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-PreFooter-768x259.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-PreFooter-16x5.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-PreFooter.png 1436w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em>Footer:<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"345\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Footer-1024x345.png\" alt=\"\" class=\"wp-image-16892\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Footer-1024x345.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Footer-300x101.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Footer-768x259.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Footer-16x5.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Footer.png 1436w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>BUSINESS CARDS:<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"345\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-BusinessCards-1024x345.png\" alt=\"\" class=\"wp-image-16900\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-BusinessCards-1024x345.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-BusinessCards-300x101.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-BusinessCards-768x259.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-BusinessCards-16x5.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-BusinessCards.png 1436w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>TRUCK:<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"600\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Truck-1024x600.png\" alt=\"\" class=\"wp-image-16903\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Truck-1024x600.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Truck-300x176.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Truck-768x450.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Truck-1536x900.png 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Truck-16x9.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Truck.png 1652w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>FOOD BOX:<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Box-1024x600.png\" alt=\"\" class=\"wp-image-16904\" width=\"480\" height=\"280\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Box-1024x600.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Box-300x176.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Box-768x450.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Box-1536x900.png 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Box-16x9.png 16w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Box.png 1652w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>OFFICE WALL:<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Wall-1024x940.png\" alt=\"\" class=\"wp-image-16906\" width=\"484\" height=\"444\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Wall-1024x940.png 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Wall-300x275.png 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Wall-768x705.png 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Wall-13x12.png 13w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2021\/06\/Logo-Wall.png 1166w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_searchwp_excluded":"1","footnotes":""},"class_list":["post-16827","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/pages\/16827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/comments?post=16827"}],"version-history":[{"count":73,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/pages\/16827\/revisions"}],"predecessor-version":[{"id":17645,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/pages\/16827\/revisions\/17645"}],"wp:attachment":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/media?parent=16827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}