{"id":31285,"date":"2022-08-08T15:35:45","date_gmt":"2022-08-08T22:35:45","guid":{"rendered":"https:\/\/www.cafoodbanks.org\/?p=31285"},"modified":"2022-08-12T16:19:11","modified_gmt":"2022-08-12T23:19:11","slug":"membermonday-efb","status":"publish","type":"post","link":"https:\/\/www.cafoodbanks.org\/es\/blog\/membermonday-efb\/","title":{"rendered":"Lunes de #: Banco de Alimentos de Emergencia Stockton \/ San Joaqu\u00edn"},"content":{"rendered":"<p><a rel=\"noreferrer noopener\" href=\"http:\/\/www.stocktonfoodbank.org\/\" target=\"_blank\">Banco de Alimentos de Emergencia Stockton\/San Joaqu\u00edn<\/a> ha servido fielmente a los residentes de Stockton y \u00e1reas circundantes durante m\u00e1s de 50 a\u00f1os, 54 para ser exactos.<\/p>\n\n\n<div class=\"media-text-block align image-left\" style=''>\r\n    <div class='media-text-block-inner'>\r\n        <div class='image'>\r\n            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/956E50C1-16B1-4168-9689-99CC212C456D-768x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/956E50C1-16B1-4168-9689-99CC212C456D-768x1024.jpeg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/956E50C1-16B1-4168-9689-99CC212C456D-225x300.jpeg 225w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/956E50C1-16B1-4168-9689-99CC212C456D-1152x1536.jpeg 1152w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/956E50C1-16B1-4168-9689-99CC212C456D-1536x2048.jpeg 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/956E50C1-16B1-4168-9689-99CC212C456D-9x12.jpeg 9w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/956E50C1-16B1-4168-9689-99CC212C456D-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>        <\/div>\r\n        <div class='text' style=''>\r\n                        <div class='content'>\r\n                                    <div class='description'><p>El Banco de Alimentos fue fundado en 1968 por un grupo de l\u00edderes comunitarios al ver la necesidad de ayudar a las personas trabajadoras que ten\u00edan dificultades para llegar a fin de mes. La misi\u00f3n del Banco de Alimentos de Emergencia es fortalecer la comunidad brindando una red de seguridad con alimentos saludables, educaci\u00f3n nutricional y esperanza a los residentes del Condado de San Joaqu\u00edn que lo necesitan. El banco de alimentos comenz\u00f3 como una organizaci\u00f3n comunitaria sin fines de lucro y contin\u00faa con el apoyo de la comunidad.<\/p>\n<\/div>\r\n                                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El dedicado personal del Banco de Alimentos de Emergencia se ha mantenido fiel a su misi\u00f3n: las puertas del Banco de Alimentos nunca han cerrado durante los m\u00e1s de dos a\u00f1os de la pandemia de COVID-19. Cuando comenzaron los cierres en marzo de 2020, el personal se adapt\u00f3 r\u00e1pidamente, ya que era necesario distribuir alimentos de forma segura a las familias necesitadas. En cuesti\u00f3n de horas, su servicio de entrega a domicilio se convirti\u00f3 en un servicio de entrega en el autom\u00f3vil, que contin\u00faa hasta el d\u00eda de hoy. Los voluntarios siguen ayudando al personal a clasificar, empaquetar y distribuir los productos.<\/p>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/fox40_Volunteers.jpg\" alt=\"\" data-id=\"31298\" data-full-url=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/fox40_Volunteers.jpg\" data-link=\"https:\/\/www.cafoodbanks.org\/blog\/membermonday-efb\/attachment\/fox40_volunteers\/\" class=\"wp-image-31298\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/fox40_Volunteers.jpg 900w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/fox40_Volunteers-300x300.jpg 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/fox40_Volunteers-150x150.jpg 150w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/fox40_Volunteers-768x768.jpg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/fox40_Volunteers-12x12.jpg 12w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/CCC_Volunteers.jpg\" alt=\"\" data-id=\"31297\" data-full-url=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/CCC_Volunteers.jpg\" data-link=\"https:\/\/www.cafoodbanks.org\/blog\/membermonday-efb\/attachment\/ccc_volunteers\/\" class=\"wp-image-31297\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/CCC_Volunteers.jpg 900w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/CCC_Volunteers-300x300.jpg 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/CCC_Volunteers-150x150.jpg 150w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/CCC_Volunteers-768x768.jpg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/CCC_Volunteers-12x12.jpg 12w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La necesidad de alimentos saludables sigue siendo grande. Su principal despensa de alimentos, ubicada en 7 West Scotts Avenue en Stockton, atiende a 30% familias m\u00e1s que en el mismo per\u00edodo de cinco meses de 2021. El Banco de Alimentos actualmente atiende a 496,000 personas m\u00e1s al a\u00f1o que antes de la pandemia.<\/p>\n\n\n\n<div style=\"height:29px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/2022_Staff-1024x683.jpg\" alt=\"\" class=\"wp-image-31299\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/2022_Staff-1024x683.jpg 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/2022_Staff-300x200.jpg 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/2022_Staff-768x512.jpg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/2022_Staff-1536x1024.jpg 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/2022_Staff-2048x1365.jpg 2048w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/2022_Staff-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"media-text-block align image-right\" style=''>\r\n    <div class='media-text-block-inner'>\r\n        <div class='image'>\r\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"990\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/626FA2F4-80B1-464E-B588-7967688F9F66-scaled-e1659998456273-1024x990.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/626FA2F4-80B1-464E-B588-7967688F9F66-scaled-e1659998456273-1024x990.jpeg 1024w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/626FA2F4-80B1-464E-B588-7967688F9F66-scaled-e1659998456273-300x290.jpeg 300w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/626FA2F4-80B1-464E-B588-7967688F9F66-scaled-e1659998456273-768x742.jpeg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/626FA2F4-80B1-464E-B588-7967688F9F66-scaled-e1659998456273-1536x1485.jpeg 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/626FA2F4-80B1-464E-B588-7967688F9F66-scaled-e1659998456273-12x12.jpeg 12w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/626FA2F4-80B1-464E-B588-7967688F9F66-scaled-e1659998456273.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>        <\/div>\r\n        <div class='text' style=''>\r\n                        <div class='content'>\r\n                                    <div class='description'><p>En 2020, el Banco de Alimentos lanz\u00f3 su programa DoorDash con San Joaqu\u00edn 211. El programa est\u00e1 dise\u00f1ado para llevar comida a residentes confinados en sus hogares. Comenz\u00f3 con un n\u00famero modesto de personas y ha crecido hasta llegar a 707 hogares por semana. El Banco de Alimentos se enorgullece de haber sido el piloto de este programa; fue gracias a la agilidad de su personal que pudieron brindar este servicio a su condado.<\/p>\n<\/div>\r\n                                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La difusi\u00f3n comunitaria disminuy\u00f3 durante la pandemia; sin embargo, desde julio de 2022, su programa de Mercados Agr\u00edcolas M\u00f3viles se ha recuperado y ahora presta servicios en 65 sitios en todo el condado de San Joaqu\u00edn. Los Educadores en Nutrici\u00f3n del Banco de Alimentos est\u00e1n colaborando con el sistema escolar p\u00fablico, ofreciendo presentaciones de alimentos saludables y entregando productos agr\u00edcolas a las aulas de primaria. Puede ver un video de un minuto de una distribuci\u00f3n del Mercado Agr\u00edcola M\u00f3vil en Stockton: <\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"DESCRIPCI\u00d3N GENERAL DEL PROGRAMA DE MERCADO M\u00d3VIL DE AGRICULTORES\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/dpRHSnBicU0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"media-text-block align image-left\" style=''>\r\n    <div class='media-text-block-inner'>\r\n        <div class='image'>\r\n            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/B53CAFAA-15DB-4F16-9A4C-8F9B7F750EB5-768x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/B53CAFAA-15DB-4F16-9A4C-8F9B7F750EB5-768x1024.jpeg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/B53CAFAA-15DB-4F16-9A4C-8F9B7F750EB5-225x300.jpeg 225w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/B53CAFAA-15DB-4F16-9A4C-8F9B7F750EB5-1152x1536.jpeg 1152w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/B53CAFAA-15DB-4F16-9A4C-8F9B7F750EB5-1536x2048.jpeg 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/B53CAFAA-15DB-4F16-9A4C-8F9B7F750EB5-9x12.jpeg 9w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/B53CAFAA-15DB-4F16-9A4C-8F9B7F750EB5-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>        <\/div>\r\n        <div class='text' style=''>\r\n                        <div class='content'>\r\n                                    <div class='description'><p>El Departamento de Educaci\u00f3n Nutricional ampli\u00f3 sus servicios y desarroll\u00f3 programas clave para apoyar a la comunidad con la educaci\u00f3n nutricional. En colaboraci\u00f3n con el Fondo Abbott, sus educadores nutricionales han establecido el programa Future Well Communities FoodRX. Aproximadamente 400 personas reciben una caja de alimentos personalizada con productos frescos e ingredientes para sus comidas, una receta para preparar los alimentos y un enlace de Zoom para una demostraci\u00f3n de cocina gratuita a cargo de sus educadores nutricionales.<\/p>\n<\/div>\r\n                                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El equipo de Educadores en Nutrici\u00f3n del Banco de Alimentos de Emergencia, junto con el Refugio de Stockton, el Equipo de Apoyo al Desarrollo del Departamento de Bomberos de Stockton, el Ej\u00e9rcito de Salvaci\u00f3n y los Centros M\u00e9dicos Comunitarios, ofrecen semanalmente servicios de asistencia social en las comunidades sin hogar de Stockton. Proporcionan alimentos nutritivos y servicios m\u00e9dicos y sociales a las personas en campamentos. Puede ver un video de un minuto sobre una despensa emergente de asistencia social aqu\u00ed: <\/p>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"DESPENSAS POP UP\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Q5hNKwLYWfE?start=3&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"media-text-block align image-left\" style=''>\r\n    <div class='media-text-block-inner'>\r\n        <div class='image'>\r\n            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/5E6A0F21-27DB-4D3B-96D7-5500C1B69139-768x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/5E6A0F21-27DB-4D3B-96D7-5500C1B69139-768x1024.jpeg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/5E6A0F21-27DB-4D3B-96D7-5500C1B69139-225x300.jpeg 225w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/5E6A0F21-27DB-4D3B-96D7-5500C1B69139-1152x1536.jpeg 1152w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/5E6A0F21-27DB-4D3B-96D7-5500C1B69139-1536x2048.jpeg 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/5E6A0F21-27DB-4D3B-96D7-5500C1B69139-9x12.jpeg 9w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/5E6A0F21-27DB-4D3B-96D7-5500C1B69139-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>        <\/div>\r\n        <div class='text' style=''>\r\n                        <div class='content'>\r\n                                    <div class='description'><p>El Banco de Alimentos de Emergencia espera con ansias su mayor recaudaci\u00f3n de fondos de un solo d\u00eda del a\u00f1o: en su 18.<sup>th<\/sup> La Carrera y Caminata Anual Contra el Hambre se celebra la ma\u00f1ana del D\u00eda de Acci\u00f3n de Gracias. Su objetivo es alcanzar los 3000 participantes este a\u00f1o. Este evento familiar y comunitario se realiza entre sus dos principales d\u00edas de distribuci\u00f3n de alimentos: la entrega anual de cajas de pavos de Acci\u00f3n de Gracias y la entrega de cajas de pavos navide\u00f1os. En un lapso de cinco horas, ambos d\u00edas, distribuyen m\u00e1s de 2000 platos navide\u00f1os completos a personas necesitadas de la comunidad.<\/p>\n<\/div>\r\n                                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:26px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"quote-block image-left align\">\r\n    <div class=\"quote-block-inner\">\r\n        <div class=\"text\">\r\n            <div class=\"quote\">\r\n                <div class=\"content\">\r\n                    Agradecemos a la Asociaci\u00f3n de Bancos de Alimentos de California (CAFB) por brindar a los bancos de alimentos de base la posibilidad de comprar alimentos con descuento. Sabemos que sin el esfuerzo de la CAFB por nosotros, no podr\u00edamos proporcionar alimentos saludables a quienes los necesitan en el condado de San Joaqu\u00edn.                    <div class=\"quotee\">Alesha Pichler, Gerente de Relaciones Comunitarias<\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"image\">\r\n            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/BE45D495-171F-46E6-A599-396A75842DFA-768x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/BE45D495-171F-46E6-A599-396A75842DFA-768x1024.jpeg 768w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/BE45D495-171F-46E6-A599-396A75842DFA-225x300.jpeg 225w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/BE45D495-171F-46E6-A599-396A75842DFA-1152x1536.jpeg 1152w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/BE45D495-171F-46E6-A599-396A75842DFA-1536x2048.jpeg 1536w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/BE45D495-171F-46E6-A599-396A75842DFA-9x12.jpeg 9w, https:\/\/www.cafoodbanks.org\/wp-content\/uploads\/2022\/08\/BE45D495-171F-46E6-A599-396A75842DFA-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>        <\/div>\r\n    <\/div>\r\n<\/div>\n\n\n<div style=\"height:32px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En CAFB agradecemos el arduo trabajo que realiza el Banco de Alimentos de Emergencia por su comunidad. Puede obtener m\u00e1s informaci\u00f3n sobre ellos en su sitio web o seguirlos en <a rel=\"noreferrer noopener\" href=\"https:\/\/www.facebook.com\/StocktonEmergencyFoodBank\" target=\"_blank\">Facebook<\/a>, <a rel=\"noreferrer noopener\" href=\"https:\/\/twitter.com\/EFBFS\" target=\"_blank\">Gorjeo<\/a>, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/emergencyfoodbank\/\" target=\"_blank\">Instagram<\/a>, <a href=\"https:\/\/www.linkedin.com\/company\/emergency-food-bank-stockton-sanjoaquin\/\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>y <a rel=\"noreferrer noopener\" href=\"https:\/\/www.youtube.com\/channel\/UCshtH4pZ9QDUrE-J9vDq6uQ\" target=\"_blank\">YouTube<\/a>.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Emergency Food Bank Stockton\/San Joaquin has faithfully served the residents of Stockton and surrounding areas for more than 50 years [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31299,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_searchwp_excluded":"","footnotes":""},"categories":[15],"tags":[248,272,72,12,182],"class_list":["post-31285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-covid-19","tag-member-food-bank","tag-mobile-food-pantries","tag-mood-booster","tag-nutrition-program"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/posts\/31285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/comments?post=31285"}],"version-history":[{"count":12,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/posts\/31285\/revisions"}],"predecessor-version":[{"id":31373,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/posts\/31285\/revisions\/31373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/media\/31299"}],"wp:attachment":[{"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/media?parent=31285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/categories?post=31285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cafoodbanks.org\/es\/wp-json\/wp\/v2\/tags?post=31285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}